{"id":39734,"date":"2025-09-25T17:22:31","date_gmt":"2025-09-25T21:22:31","guid":{"rendered":"https:\/\/www.halfyourplate.ca\/blog\/comment-aider-votre-tout-petit-a-apprendre-a-aimer-les-legumes-sans-pression\/"},"modified":"2025-09-25T17:22:36","modified_gmt":"2025-09-25T21:22:36","slug":"comment-aider-votre-tout-petit-a-apprendre-a-aimer-les-legumes-sans-pression","status":"publish","type":"post","link":"https:\/\/www.halfyourplate.ca\/fr\/blog\/comment-aider-votre-tout-petit-a-apprendre-a-aimer-les-legumes-sans-pression\/","title":{"rendered":"Comment aider votre tout-petit \u00e0 apprendre \u00e0 aimer les l\u00e9gumes, sans pression"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">par Jessica\u00a0Penner, di\u00e9t\u00e9tiste autoris\u00e9e, et Nita\u00a0Sharda, di\u00e9t\u00e9tiste autoris\u00e9e (Happy Healthy Eaters)<\/p>\n\n<p class=\"wp-block-paragraph\">Si vous avez d\u00e9j\u00e0 \u00e9prouv\u00e9 de la frustration \u00e0 l\u2019\u00e9gard de votre tout-petit qui <em>refuse<\/em> de manger ses l\u00e9gumes, vous n\u2019\u00eates pas un cas isol\u00e9. \u00c9norm\u00e9ment de parents \u00e9prouvent la m\u00eame difficult\u00e9\u00a0: leur tout-petit prend souvent plaisir \u00e0 manger des fruits, mais tire la langue lorsqu\u2019on leur pr\u00e9sente des l\u00e9gumes verts. Cela peut \u00eatre d\u00e9courageant, en particulier si vous faites de votre mieux pour lui inculquer de bonnes habitudes alimentaires.<\/p>\n\n<p class=\"wp-block-paragraph\">Mais que disent les statistiques? Les tout-petits ne sont pas les seuls \u00e0 \u00e9viter les l\u00e9gumes. Pr\u00e8s de <strong>90\u00a0% des Canadiens<\/strong> ne consomment pas la quantit\u00e9 de fruits et l\u00e9gumes recommand\u00e9e au quotidien. Bien que les donn\u00e9es nationales concernant les jeunes enfants soient limit\u00e9es, on peut dire sans crainte de se tromper que les tout-petits n\u2019en mangent pas non plus assez, surtout parce que les l\u00e9gumes ne font pas envie.<\/p>\n\n<p class=\"wp-block-paragraph\">Mais nous sommes des mamans d\u2019abord, et des di\u00e9t\u00e9tistes ensuite. Ayant eu quatre enfants qui ont travers\u00e9 les ann\u00e9es de rejet de la nourriture, nous pouvons vous confirmer que <em>vous pouvez aider votre enfant \u00e0 apprendre \u00e0 aimer les l\u00e9gumes<\/em>.<br\/><br\/>Mais avant de vous donner nos conseils, nous voulions aborder un sujet important&#8230;<\/p>\n\n<h2 class=\"wp-block-heading\">Lorsque la pression s\u2019invite \u00e0 la table<\/h2>\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1275\" src=\"https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/iStock-1167082925-scaled.jpg\" alt=\"\" class=\"wp-image-39722\" style=\"width:550px\" srcset=\"https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/iStock-1167082925-scaled.jpg 1920w, https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/iStock-1167082925-300x199.jpg 300w, https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/iStock-1167082925-1024x680.jpg 1024w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-element-caption\">Concept d\u2019alimentation saine. Un petit gar\u00e7on heureux mange diff\u00e9rents types de l\u00e9gumes, comme des carottes, du chou-fleur et du brocoli, dans une cuisine.<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Il est tout \u00e0 fait normal de s\u2019inqui\u00e9ter des habitudes alimentaires de son tout-petit. <em>Mange-t-il suffisamment? Mange-t-il trop? Pourquoi refuse-t-il soudainement de manger des l\u00e9gumes qu\u2019il aimait?<\/em><\/p>\n\n<p class=\"wp-block-paragraph\">Lorsque l\u2019inqui\u00e9tude prend le dessus, la pression peut facilement s\u2019immiscer \u2013 parfois m\u00eame sans qu\u2019on s\u2019en rende compte. Mais voici la dure r\u00e9alit\u00e9\u00a0: la pression finira par se retourner contre vous. Cette technique pourrait fonctionner \u00e0 court terme, mais \u00e0 long terme, cela pourrait engendrer des tensions \u00e0 l\u2019heure du repas, rendre votre enfant m\u00e9fiant et le pousser \u00e0 moins comprendre sa faim et ses signes de sati\u00e9t\u00e9.<\/p>\n\n<p class=\"wp-block-paragraph\">Voici quelques exemples courants de pression\u00a0:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>\u00ab\u00a0Encore trois bouch\u00e9es, et tu pourras avoir ton dessert.\u00a0\u00bb<\/li>\n\n\n\n<li>\u00ab\u00a0Tu aimais \u00e7a hier, pourquoi ne le manges-tu pas aujourd\u2019hui?\u00a0\u00bb<\/li>\n\n\n\n<li>\u00ab\u00a0Allez, mange pour maman!\u00a0\u00bb<\/li>\n\n\n\n<li>Cacher des l\u00e9gumes dans la nourriture sans lui dire.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Bien qu\u2019il soit naturel de vouloir que son enfant mange, ce n\u2019est pas notre travail de le forcer \u00e0 manger. Notre travail consiste \u00e0 lui offrir divers aliments dans un environnement positif, et \u00e0 le laisser choisir les aliments et la quantit\u00e9 qu\u2019il veut manger.<\/p>\n\n<p class=\"wp-block-paragraph\">Cela dit, voici quelques fa\u00e7ons d\u2019aider votre enfant \u00e0 aimer les l\u00e9gumes.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong><br\/>Trois fa\u00e7ons d\u2019aider votre tout-petit \u00e0 aimer les l\u00e9gumes<\/strong><\/h2>\n\n<h3 class=\"wp-block-heading\">1. Servez-les avec une trempette<\/h3>\n\n<p class=\"wp-block-paragraph\">Les l\u00e9gumes sont naturellement amers, et comme les jeunes enfants ont plus de papilles gustatives que les adultes, cette amertume peut \u00eatre encore plus forte. Et c\u2019est sans compter que les b\u00e9b\u00e9s et les tout-petits sont biologiquement programm\u00e9s pour pr\u00e9f\u00e9rer les saveurs sucr\u00e9es. Les premi\u00e8res choses qu\u2019ils go\u00fbtent \u2013 le liquide amniotique dans l\u2019ut\u00e9rus et le colostrum des seins \u2013 sont sucr\u00e9es, surtout lorsqu\u2019on les compare \u00e0 du brocoli!<\/p>\n\n<p class=\"wp-block-paragraph\">En sachant cela, on peut mieux comprendre pourquoi nos tout-petits sont obstin\u00e9s. Pour les aider \u00e0 manger des l\u00e9gumes, on peut notamment servir ces derniers avec une trempette ou de la sauce. Les enfants <em>adorent<\/em> tremper leurs aliments, et les options de trempettes ne manquent pas\u00a0: la sauce ranch, le ketchup, le sirop d\u2019\u00e9rable, l\u2019houmous, la sauce tzatziki et le labneh peuvent tous rendre les l\u00e9gumes plus attrayants et l\u2019exp\u00e9rience plus amusante.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2015\/01\/Carrot-dip-2-200x300.jpg\" alt=\"\" class=\"wp-image-38577\" srcset=\"https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2015\/01\/Carrot-dip-2-200x300.jpg 200w, https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2015\/01\/Carrot-dip-2-683x1024.jpg 683w, https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2015\/01\/Carrot-dip-2.jpg 836w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><figcaption class=\"wp-element-caption\">Hors-d\u2019\u0153uvre v\u00e9g\u00e9tarien. Une trempette aux carottes et du pain azyme avec une vinaigrette au s\u00e9same et du persil en arri\u00e8re-plan.<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Voici quelques id\u00e9es de trempettes amusantes \u00e0 essayer. Vous pouvez aussi laisser votre enfant choisir!<\/p>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.halfyourplate.ca\/fr\/recipe\/biscottes-de-pita-aux-fines-herbes-cuites-au-four-et-trempette-de-carottes-roties-2\/\">Trempette aux carottes r\u00f4ties<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.halfyourplate.ca\/fr\/recipe\/trempette-aux-betteraves\/\">Trempette aux betteraves r\u00f4ties<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.halfyourplate.ca\/fr\/recipe\/baba-ganoush-trempette-daubergines\/\">Trempette aux aubergines r\u00f4ties<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.halfyourplate.ca\/fr\/blog\/4-trempettes-pour-accompagner-les-crudites\/\">4\u00a0autres trempettes pour accompagner les crudit\u00e9s<\/a><\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">2. <strong>Incorporez des l\u00e9gumes \u00e0 des plats d\u00e9j\u00e0 adopt\u00e9s<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Soyons r\u00e9alistes\u00a0: les l\u00e9gumes ne sont pas toujours app\u00e9tissants pour les tout-petits. Mais en <em>ajoutant<\/em> des l\u00e9gumes dans des plats que votre enfant aime d\u00e9j\u00e0, vous les rendrez plus accessibles et augmenterez la probabilit\u00e9 que votre enfant les mange.<\/p>\n\n<p class=\"wp-block-paragraph\">Id\u00e9es\u00a0:<br\/>\u00a0\ud83e\udd55 Carottes dans des muffins<br\/>\u00a0\ud83c\udf31 \u00c9pinards dans des <a href=\"https:\/\/www.halfyourplate.ca\/fr\/recipe\/frappe-a-la-mangue-et-a-la-banane\/\">smoothies<\/a><br\/>\u00a0\ud83c\udf5d Une sauce pour p\u00e2tes pleine de l\u00e9gumes au go\u00fbt r\u00e9confortant<\/p>\n\n<p class=\"wp-block-paragraph\">Nous aimons particuli\u00e8rement cette <strong><u>sauce pour p\u00e2tes pleine de l\u00e9gumes<\/u><\/strong>, qui combine sept l\u00e9gumes diff\u00e9rents en une d\u00e9licieuse sauce riche. Chaque bol contient trois portions compl\u00e8tes de l\u00e9gume et ravit les tout-petits! Les p\u00e2tes \u00e0 la rescousse!<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"320\" src=\"https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/Picture4.jpg\" alt=\"\" class=\"wp-image-39714\" srcset=\"https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/Picture4.jpg 480w, https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/Picture4-300x200.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n<\/div>\n<blockquote class=\"wp-block-quote has-text-align-left alignleft is-style-default has-black-color has-white-background-color has-text-color has-background has-link-color has-large-font-size wp-elements-1 is-layout-flow wp-block-quote-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Mais&#8230; cachons-nous les l\u00e9gumes? <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Pas tout \u00e0 fait. Vous remarquerez que cette sauce n\u2019est pas une sauce aux \u00ab\u00a0l\u00e9gumes cach\u00e9s\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous vous recommandons de rendre les l\u00e9gumes <em>visibles<\/em> et <em>accessibles<\/em> au lieu de les cacher. Si votre enfant d\u00e9couvre qu\u2019il y a des courgettes ou du c\u00e9leri dans son repas sans que vous lui ayez dit, cela pourrait rompre votre lien de confiance. Cela \u00e9veillera encore plus la m\u00e9fiance de votre enfant, ce que nous voulons \u00e9viter \u00e0 tout prix.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parlez plut\u00f4t ouvertement des l\u00e9gumes qui se trouvent dans le plat. Demandez \u00e0 votre enfant de vous aider \u00e0 laver les poivrons rouges ou de d\u00e9poser les carottes hach\u00e9es dans la po\u00eale. Il faut amener nos enfants \u00e0 aimer les l\u00e9gumes parce qu\u2019ils go\u00fbtent bon, pas parce qu\u2019on leur en a fait manger par la ruse.<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h3 class=\"wp-block-heading\">3. Continuez de leur offrir des l\u00e9gumes, m\u00eame si cela semble sans espoir<\/h3>\n\n<p class=\"wp-block-paragraph\">Lorsqu\u2019on est parent, on re\u00e7oit beaucoup de conseils sur la fa\u00e7on de nourrir ses enfants, mais les recherches sont sans \u00e9quivoque\u00a0: l\u2019exposition r\u00e9p\u00e9t\u00e9e est efficace.<\/p>\n\n<p class=\"wp-block-paragraph\">Les tout-petits doivent voir, toucher et sentir les aliments \u00e0 de <em>nombreuses<\/em> reprises avant d\u2019\u00eatre pr\u00eats \u00e0 y go\u00fbter et \u00e0 les manger. Bien que le nombre d\u2019expositions exact varie d\u2019un enfant \u00e0 l\u2019autre (et d\u2019un l\u00e9gume \u00e0 l\u2019autre), les <a href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC8143368\/\" rel=\"nofollow noopener\" target=\"_blank\">\u00e9tudes indiquent qu\u2019il faut au moins 4 \u00e0 10\u00a0expositions<\/a> avant qu\u2019un enfant accepte non seulement un l\u00e9gume, mais soit plus ouvert \u00e0 l\u2019id\u00e9e de manger d\u2019autres types l\u00e9gumes.<\/p>\n\n<p class=\"wp-block-paragraph\">N\u2019oubliez pas non plus qu\u2019une grimace de d\u00e9go\u00fbt ne signifie pas n\u00e9cessairement que votre tout-petit n\u2019aime pas ce qu\u2019il vient de manger. Les tout-petits ont besoin de temps pour reconna\u00eetre un aliment, d\u00e9terminer ce qui est s\u00e9curitaire et ressentir la texture dans la bouche. Une grimace pourrait tout simplement vouloir dire \u00ab\u00a0C\u2019est nouveau\u00a0\u00bb, et non \u00ab\u00a0Ce n\u2019est pas bon\u00a0\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">Les enfants ne peuvent pas apprendre \u00e0 aimer un aliment qu\u2019ils ne voient jamais \u00e0 table. Donc, m\u00eame lorsque votre tout-petit refuse encore de manger le <a href=\"https:\/\/www.halfyourplate.ca\/fr\/produce\/legumes\/brocoli\/\">brocoli<\/a> que vous venez de lui servir, n\u2019abandonnez pas. Essayez de le servir de diff\u00e9rentes fa\u00e7ons\u00a0: r\u00f4ti, avec une trempette, m\u00e9lang\u00e9 \u00e0 des p\u00e2tes \u2013 et maintenez une ambiance positive. Au fil du temps, ces expositions r\u00e9p\u00e9t\u00e9es peuvent renforcer la confiance et la curiosit\u00e9.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Conclusion<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Les l\u00e9gumes et les tout-petits ne font pas toujours bon m\u00e9nage, mais cela ne signifie pas que vous vous y preniez mal. Vous savez maintenant qu\u2019il est normal que les jeunes enfants h\u00e9sitent \u00e0 manger des l\u00e9gumes.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/iStock-2027637709-300x200.jpg\" alt=\"\" class=\"wp-image-39726\" srcset=\"https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/iStock-2027637709-300x200.jpg 300w, https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/iStock-2027637709-1024x683.jpg 1024w, https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/iStock-2027637709-scaled.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption class=\"wp-element-caption\">Photo d\u2019un adorable petit gar\u00e7on assis devant une table, fourchette \u00e0 la main, qui mange un d\u00e9licieux d\u00eener sain. Un enfant heureux mange son repas et regarde l\u2019appareil-photo. Un gar\u00e7on mange.<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Vous rappelez-vous que nous vous avons dit au d\u00e9but de l\u2019article, que <strong>90\u00a0% des Canadiens<\/strong> ne consommaient pas la quantit\u00e9 de fruits et l\u00e9gumes recommand\u00e9e au quotidien? Envisagez de changer un peu votre alimentation pour accro\u00eetre votre propre consommation; n\u2019oubliez pas que les enfants aiment reproduire ce qu\u2019ils voient! Et voil\u00e0, un conseil en plus!<\/p>\n\n<p class=\"wp-block-paragraph\">En faisant preuve de constance, en \u00e9vitant de mettre de la pression \u00e0 vos enfants, en faisant preuve de cr\u00e9ativit\u00e9 pour les repas familiaux et en offrant des l\u00e9gumes de diff\u00e9rentes fa\u00e7ons (et \u00e0 de multiples reprises!), vous faites exactement ce dont vos enfants ont besoin. L\u2019important n\u2019est pas d\u2019atteindre la perfection; c\u2019est de renforcer la confiance, l\u2019exposition et la relation positive \u00e0 long terme avec la nourriture.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"320\" src=\"https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/Picture2.jpg\" alt=\"\" class=\"wp-image-39716\" srcset=\"https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/Picture2.jpg 480w, https:\/\/www.halfyourplate.ca\/wp-content\/uploads\/2025\/09\/Picture2-300x200.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\">\u00c0 propos des auteures\u00a0: <\/h2>\n\n<p class=\"wp-block-paragraph\">Jessica\u00a0Penner et Nita\u00a0Sharda sont di\u00e9t\u00e9tistes autoris\u00e9es et sp\u00e9cialis\u00e9es en alimentation des enfants. Vous pouvez communiquer avec elles pour obtenir un soutien nutritionnel et trouver plus recettes sur le site <a href=\"http:\/\/www.happyhealthyeaters.com\" rel=\"nofollow noopener\" target=\"_blank\">www.happyhealthyeaters.com<\/a> (en anglais seulement).<\/p>\n\n<p class=\"wp-block-paragraph\"><a id=\"_msocom_1\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>par Jessica\u00a0Penner, di\u00e9t\u00e9tiste autoris\u00e9e, et Nita\u00a0Sharda, di\u00e9t\u00e9tiste autoris\u00e9e (Happy Healthy Eaters) Si vous avez d\u00e9j\u00e0 \u00e9prouv\u00e9 de la frustration \u00e0&#8230;<\/p>\n","protected":false},"author":423,"featured_media":39723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","wpupg_custom_link":[],"wpupg_custom_link_behaviour":[],"wpupg_custom_link_nofollow":[],"wpupg_custom_image":[],"wpupg_custom_image_id":[],"footnotes":""},"categories":[5067],"tags":[5612,6287,6286],"class_list":["post-39734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogues-et-informations","tag-apprecie-des-enfants-fr","tag-satisfaction-des-capricieux","tag-tout-petit"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.halfyourplate.ca\/fr\/wp-json\/wp\/v2\/posts\/39734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.halfyourplate.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.halfyourplate.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.halfyourplate.ca\/fr\/wp-json\/wp\/v2\/users\/423"}],"replies":[{"embeddable":true,"href":"https:\/\/www.halfyourplate.ca\/fr\/wp-json\/wp\/v2\/comments?post=39734"}],"version-history":[{"count":1,"href":"https:\/\/www.halfyourplate.ca\/fr\/wp-json\/wp\/v2\/posts\/39734\/revisions"}],"predecessor-version":[{"id":39735,"href":"https:\/\/www.halfyourplate.ca\/fr\/wp-json\/wp\/v2\/posts\/39734\/revisions\/39735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.halfyourplate.ca\/fr\/wp-json\/wp\/v2\/media\/39723"}],"wp:attachment":[{"href":"https:\/\/www.halfyourplate.ca\/fr\/wp-json\/wp\/v2\/media?parent=39734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.halfyourplate.ca\/fr\/wp-json\/wp\/v2\/categories?post=39734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.halfyourplate.ca\/fr\/wp-json\/wp\/v2\/tags?post=39734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}